{"id":1679,"date":"2024-01-15T17:30:12","date_gmt":"2024-01-15T17:30:12","guid":{"rendered":"http:\/\/myshellty.com\/?page_id=1679"},"modified":"2024-09-04T09:40:08","modified_gmt":"2024-09-04T09:40:08","slug":"termos-e-condicoes","status":"publish","type":"page","link":"https:\/\/myshellty.com\/pt\/termos-e-condicoes\/","title":{"rendered":"Termos e Condi\u00e7\u00f5es"},"content":{"rendered":"\n\t\t<div id=\"termos-e-condicoes\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section parallax_section top_padding_tablet_100px top_padding_phone_50px bottom_padding_tablet_100px bottom_padding_phone_50px\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"zoom-out-slow\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\" data-parallax-speed=\"slow\" style=\"background-position: left top; background-repeat: no-repeat; background-color: #ffffff; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: #f2f2f2; background: linear-gradient(to bottom,#f2f2f2 0%,#ffffff 100%);  opacity: 1; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div style=\" color: #1a1f3c;\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \" data-cfc=\"true\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h1>Termos e Condi\u00e7\u00f5es<\/h1>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 35px; height: 2px; margin-bottom: 35px;\" data-width=\"100%\" data-animate=\"\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1725442784849\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\" translation-block\">Em conformidade com a Lei n.\u00ba 47\/2014, de 28 de Julho, o presente documento estabelece as condi\u00e7\u00f5es a observar no uso do site www.ihcarehealth.com, bem como no processo de compra de produtos colocados \u00e0 disposi\u00e7\u00e3o dos seus utilizadores.<\/p>\n<p>Com efeito, solicitamos que leia atentamente as condi\u00e7\u00f5es e a pol\u00edtica de privacidade antes de utilizar o site, uma vez que ao fazer uso do mesmo ou ao efetuar uma encomenda, o cliente est\u00e1 a consentir a sua vincula\u00e7\u00e3o \u00e0s supracitadas condi\u00e7\u00f5es<\/p>\n<p>Por isso, e caso o utilizador n\u00e3o concorde com todas as condi\u00e7\u00f5es e com a pol\u00edtica de privacidade n\u00e3o dever\u00e1 utilizar a p\u00e1gina web, www.ihcarehealth.com <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a><\/p>\n<p class=\" translation-block\">Estes Termos e Condi\u00e7\u00f5es (os &#8220;Termos&#8221;) aplicam-se a todas as encomendas e compras de produtos da Ihcare &#8211; Innovation Hospital Care daqui em diante como &#8220;IHCare&#8221;, &#8220;Empresa&#8221;, &#8220;n\u00f3s&#8221;, &#8220;nos&#8221; ou &#8220;nosso&#8221;) feitas atrav\u00e9s do Website da IHCare (www.ihcarehealth.com) ou atrav\u00e9s de quaisquer outras plataformas digitais (coletivamente o &#8220;Website&#8221;) onde apresentamos estes Termos. O presente contrato \u00e9 celebrado com a Ihcare &#8211; Innovation Hospital Care, com sede em Quinta Vale do Espinhal, EM558 1, 3230-343 Penela, com o NIF 510889450. O Website permite-lhe conhecer e adquirir os nossos os Produtos, al\u00e9m de lhe permitir interagir com a IHCare. A qualquer momento, a IHCare pode alterar, suspender ou descontinuar qualquer funcionalidade do Website, incluindo as horas de funcionamento ou acessibilidade do Website ou a disponibilidade de qualquer Produto ou funcionalidade, sem a necessidade de fornecer qualquer tipo de aviso pr\u00e9vio ao utilizador. A utiliza\u00e7\u00e3o do Website, coletivamente, os &#8220;Produtos&#8221; est\u00e3o sujeitos (i) aos Termos, (ii) \u00e0 Pol\u00edtica de Privacidade aplic\u00e1vel. Por favor, leia atentamente todos os documentos acima indicados. Quando encomenda diretamente do Website ou atrav\u00e9s de qualquer outra p\u00e1gina web diretamente ligada ao Website, est\u00e1 a indicar-nos que concorda com os Termos tal como aqui est\u00e3o escritos. Durante o checkout, o cliente ter\u00e1 de indicar expressamente a aceita\u00e7\u00e3o destes Termos. S\u00f3 \u00e9 poss\u00edvel existir um desvio a estes Termos se tal for acordado por escrito pela IHCare. Se n\u00e3o concordar com estes Termos, o utilizador dever\u00e1 abster-se de utilizar Website agora ou no futuro. Se tiver alguma d\u00favida sobre os Termos, por favor contacte-nos atrav\u00e9s do e-mail\u00a0support@ihcare.pt. A IHCare poder\u00e1 oferecer os Produtos atrav\u00e9s de outros canais de distribui\u00e7\u00e3o autorizados, tais como outros vendedores e websites; nesse caso, os termos, condi\u00e7\u00f5es e pol\u00edticas aplic\u00e1veis a esses vendedores poder\u00e3o ser diferentes dos presentes Termos.<\/p>\n<p>Entidade gestora do site: IHcare SA<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 1: ENCOMENDA<\/strong><\/h3>\n<p>1. O utilizador poder\u00e1 efetuar a sua encomenda online, na p\u00e1gina web, <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a><br \/>\n2. Para realizar a encomenda, o utilizador dever\u00e1 preencher todos os campos obrigat\u00f3rios, devendo facultar os seus dados pessoais, tendo sempre presente a nossa pol\u00edtica de privacidade para assegurar o tratamento dos mesmos.<br \/>\n3. Ao efetuar a sua encomenda, o utilizador manifesta a sua aceita\u00e7\u00e3o, plena e completa, das condi\u00e7\u00f5es gerais de venda, dos pre\u00e7os e da descri\u00e7\u00e3o dos produtos contemplados nessa transa\u00e7\u00e3o.<br \/>\n4. Todas as encomendas est\u00e3o sujeitas \u00e0 aceita\u00e7\u00e3o da iHCare SA, da qual o utilizador ser\u00e1 informado mediante correio eletr\u00f3nico.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 2: DISPONIBILIDADE DO PRODUTO<\/strong><\/h3>\n<p>1. Todas as encomendas de produtos est\u00e3o sujeitas \u00e0 disponibilidade dos mesmos.<br \/>\n2. A inexist\u00eancia dos produtos encomendados em stock ou qualquer outra causa de impossibilidade de fornecimento dos produtos encomendados, ser\u00e1 informada pela iHCare SA.<br \/>\n3. No caso previsto no n\u00famero anterior a iHCare SA, reembolsar\u00e1 o utilizador dos montantes que eventualmente tenha pago, conforme o disposto no art. 19\u00ba do supra citado diploma.<br \/>\n4. A iHCare SA reserva o direito de retirar qualquer produto da p\u00e1gina www.ihcarehealth.com, em qualquer momento e de suprimir ou modificar qualquer material ou conte\u00fado da mesma. <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com.<\/a><br \/>\n5. A iHCare SA n\u00e3o se responsabiliza, perante o utilizador ou terceiro, por retirar qualquer produto da p\u00e1gina, www.ihcarehealth.com bem como pela falta de disponibilidade do produto nos termos do n\u00famero 1 e 3 da presente cl\u00e1usula.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 3: IMPOSSIBILIDADE DE CONCLUIR UMA ENCOMENDA<\/strong><\/h3>\n<p>A iHCare SA n\u00e3o assume qualquer responsabilidade pela recusa de conclus\u00e3o da encomenda derivada de circunst\u00e2ncias excecionais, mesmo ap\u00f3s confirma\u00e7\u00e3o da mesma, tendo apenas a obriga\u00e7\u00e3o de comunicar ao utilizador\/cliente a impossibilidade de conclus\u00e3o da encomenda e proceder \u00e0 devolu\u00e7\u00e3o dos pagamentos efetuados.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 4: ENTREGA<\/strong><\/h3>\n<p>1. Sem preju\u00edzo do estabelecido no artigo 2\u00ba, relativo \u00e0 disponibilidade dos produtos, a encomenda ser\u00e1 enviada no prazo de 10 dias \u00fateis ap\u00f3s confirma\u00e7\u00e3o do pagamento.<br \/>\n2. O cumprimento do prazo referido no n\u00famero anterior pode ser livremente alterado pela iHCare SA, designadamente na ocorr\u00eancia de circunst\u00e2ncias excecionais, imprevistas, e dependendo da zona a efetuar a entrega.<br \/>\n3. A iHCare SA, apenas procede ao envio da encomenda ap\u00f3s liquida\u00e7\u00e3o do pre\u00e7o da totalidade dos produtos encomendados, bem como dos respetivos custos de envio.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 5: CUSTOS DA ENTREGA<\/strong><\/h3>\n<p>1. A ihcare suportar\u00e1 os custos com a entrega dos Produtos no endere\u00e7o indicado por si no momento da encomenda dentro do territ\u00f3rio portugu\u00eas, incluindo as Regi\u00f5es Aut\u00f3nomas dos A\u00e7ores e Madeira.<br \/>\na) Entrega em Alemanha, \u00c1ustria, B\u00e9lgica, Dinamarca, Espanha continental, Fran\u00e7a continental, Irlanda, It\u00e1lia, Luxemburgo, Pa\u00edses Baixos, Reino Unido, de produtos de montante igual ou inferior a \u20ac 300,00 (trezentos euros) &#8211; custo adicional de \u20ac 10,90 (dez euros e noventa c\u00eantimos);<br \/>\nb) Entrega em Alemanha, \u00c1ustria, B\u00e9lgica, Dinamarca, Espanha continental, Fran\u00e7a continental, Irlanda, It\u00e1lia, Luxemburgo, Pa\u00edses Baixos, Reino Unido, de produtos de montante superior a \u20ac 300,00 (trezentos euros) &#8211; sem custo adicional.<br \/>\n2. Os custos identificados no n\u00famero um da presente cl\u00e1usula podem ser alterados pela iHCare SA, sem aviso pr\u00e9vio.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 6: IMPOSSIBILIDADE DE ENTREGA<\/strong><\/h3>\n<p>1. As entregas s\u00e3o efetuadas de segunda-feira a sexta-feira, devendo o utilizador\/cliente indicar a morada onde pretende receber a encomenda.<br \/>\n2. No caso de impossibilidade do utilizador se encontrar no local para entrega da encomenda, deve indicar morada alternativa ou contactar-nos pelos meios disponibilizados no website\u00a0 <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a><br \/>\n3. A IHCare n\u00e3o se responsabiliza por atrasos que ocorram por circunst\u00e2ncia fora do nosso controlo. Se a entrega do(s) produtos for atrasada devido a um evento fora do nosso controlo, entraremos em contacto com o utilizador o mais rapidamente poss\u00edvel para o informar e tomar medidas para minimizar o efeito do atraso. Se houver um risco de atraso na entrega, o utilizador pode contactar-nos para rescindir o contrato e receber um reembolso por qualquer produto(s) pago(s) mas n\u00e3o recebido(s).<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 7: PRE\u00c7O E PAGAMENTO<\/strong><\/h3>\n<p>1. Em conformidade com as normas e os regulamentos em vigor, os pre\u00e7os estabelecidos na p\u00e1gina Web www.ihcarehealth.com, devem entender-se em euros, com taxas e impostos inclu\u00eddos.<\/p>\n<p>2. Os pre\u00e7os apresentados t\u00eam em conta o Imposto sobre o Valor Acrescentado (IVA) aplic\u00e1vel \u00e0 data da fatura.<\/p>\n<p class=\" translation-block\">3. De acordo com o estabelecido no Cap\u00edtulo I, T\u00edtulo V, da Diretiva 2006\/112\/CE do Conselho, de 28 de Novembro de 2006, relativa ao sistema comum do IVA, o local do fornecimento considera-se ser o do Estado-Membro onde se situa a morada onde os produtos dever\u00e3o ser entregues e a taxa de IVA aplic\u00e1vel ser\u00e1 a que estiver em vigor no Estado-Membro do local do fornecimento, de acordo com as encomendas efetuadas. Segundo as normas e os regulamentos aplic\u00e1veis em cada jurisdi\u00e7\u00e3o, o sistema de autoliquida\u00e7\u00e3o (artigo 194.\u00ba da Diretiva 2006\/112\/CE) aplica-se a produtos fornecidos em alguns Estados-Membros da Uni\u00e3o Europeia, no caso de o consumidor ser ou dever ser um sujeito passivo de IVA. Neste caso, n\u00e3o liquidaremos o IVA, ficando sujeito a confirma\u00e7\u00e3o por parte do destinat\u00e1rio dos produtos de que o IVA devido ser\u00e1 liquidado pelo cliente, nos termos do sistema de autoliquida\u00e7\u00e3o.<\/p>\n<p>4. Os pre\u00e7os e especifica\u00e7\u00f5es est\u00e3o sujeitos a altera\u00e7\u00f5es, sem aviso pr\u00e9vio.<\/p>\n<p>5. A IHCare S.A. fez todos os esfor\u00e7os para disponibilizar a informa\u00e7\u00e3o atualizada, correta e clara. No entanto, \u00e9 poss\u00edvel que possam ocorrer erros em informa\u00e7\u00f5es publicadas. A IHCare S.A. declina qualquer responsabilidade por erros involunt\u00e1rios e precis\u00e3o de qualquer informa\u00e7\u00e3o que possa estar contida na p\u00e1gina web.<\/p>\n<p>6. No tratamento da sua encomenda todo e qualquer erro de pre\u00e7os que eventualmente possa ser apresentado no site, devido a anomalias t\u00e9cnicas, ser\u00e1 detetado.<\/p>\n<p>7. O utilizador\/cliente ser\u00e1 contactado para a aceitar ou cancelar a encomenda, no caso do pre\u00e7o real do produto encomendado ser superior ao constante na p\u00e1gina.<\/p>\n<p>8. Se o pre\u00e7o real do produto encomendado for inferior ao apresentado na p\u00e1gina \u00e9 devolvida a diferen\u00e7a entre o pre\u00e7o real e o pre\u00e7o pago.<\/p>\n<p>9. O utilizador pode utilizar os seguintes modos de pagamento:<\/p>\n<ul>\n<li>a) Cart\u00e3o de Cr\u00e9dito (VISA e MASTERCARD);<\/li>\n<li>b) MB Way<\/li>\n<li>c) Multibanco<\/li>\n<li>d) Pagamento em 3x Klarna<\/li>\n<\/ul>\n<p>10. Para utiliza\u00e7\u00e3o do modo de pagamento identificado na al\u00ednea a) fica sujeito ao envio dos dados da encomenda e do cart\u00e3o do utilizador\/cliente, devidamente encriptados, para a entidade banc\u00e1ria na data da encomenda, sendo a encomenda processada ap\u00f3s valida\u00e7\u00e3o e comunica\u00e7\u00e3o ao banco do utilizador e cancelada em caso de recusa do banco do utilizador\/cliente.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 8: TRANSFER\u00caNCIA DOS RISCOS<\/strong><\/h3>\n<p>1. Os riscos dos produtos estar\u00e3o a cargo do utilizador\/cliente a partir do momento da sua entrega.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 9: DIREITO DE DESIST\u00caNCIA DA COMPRA E DEVOLU\u00c7\u00c3O<\/strong><\/h3>\n<p>1. De acordo com as normas aplic\u00e1veis nos artigos 10\u00ba a 17\u00ba do Decreto-Lei n\u00ba 24\/2014 de 14 de Fevereiro, o utilizador\/cliente poder\u00e1 desistir do contrato, sem indica\u00e7\u00e3o de motivo, no prazo de 14 dias a contar da data de entrega da encomenda, somente os itens encomendados ser\u00e3o reembolsados.<\/p>\n<p>2. Os custos de envio e de devolu\u00e7\u00e3o est\u00e3o a cargo do cliente.<\/p>\n<p>3. O cliente poder\u00e1 exercer o direito de desist\u00eancia por qualquer forma admitida por lei, considerando-se, de qualquer maneira, validamente exercido esse direito mediante o envio de informa\u00e7\u00e3o de desist\u00eancia.<\/p>\n<p>4. Esta disposi\u00e7\u00e3o n\u00e3o afeta os outros direitos reconhecidos ao consumidor pela legisla\u00e7\u00e3o em vigor.<\/p>\n<p>5. Os custos de devolu\u00e7\u00e3o dos (s) produtos (s) s\u00e3o da responsabilidade do utilizador\/cliente, pelo que no caso de envio \u00e0 cobran\u00e7a determina a possibilidade da iHCare SA cobrar as despesas em que possa incorrer.<\/p>\n<p>6. O direito de desist\u00eancia do Contrato pelo utilizador\/cliente nos termos do disposto no n.\u00ba 1 do presente artigo aplica-se, exclusivamente, aos produtos que possam ser devolvidos nas mesmas condi\u00e7\u00f5es em que o utilizador\/cliente os recebeu, designadamente na embalagem original e com todos os documentos.<\/p>\n<p>7. Ap\u00f3s devolu\u00e7\u00e3o, o produto ser\u00e1 examinado pela iHCare SA, que verificar\u00e1 as condi\u00e7\u00f5es do mesmo.<\/p>\n<p>8. N\u00e3o ser\u00e1 efetuado reembolso se o produto tiver sido utilizado para al\u00e9m da simples abertura da respetiva embalagem ou se tiver sofrido danos.<\/p>\n<p>9. A devolu\u00e7\u00e3o efetuar-se-\u00e1 com a maior brevidade poss\u00edvel.<\/p>\n<p>10. A responsabilidade pelos danos sofridos pelos produtos, bem como o extravio dos mesmos, durante a devolu\u00e7\u00e3o, s\u00e3o da exclusiva responsabilidade do utilizador\/cliente.<\/p>\n<p>11. Morada de devolu\u00e7\u00e3o:<\/p>\n<p>iHCare AS<br \/>\nRua Carlos Pinto de Abreu 5N<br \/>\n3040-245 Coimbra<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 10: DEVOLU\u00c7\u00c3O DE PRODUTOS COM DEFEITO<\/strong><\/h3>\n<p>1. Nos casos em que considere que, no momento da entrega, o produto n\u00e3o est\u00e1 de acordo com as disposi\u00e7\u00f5es do contrato, o utilizador\/cliente dever\u00e1 contactar de imediato a iHCare SA.<\/p>\n<p>2. A recolha do produto em desconformidade com as condi\u00e7\u00f5es do contrato ser\u00e1 efetuada pela iHCare SA.<\/p>\n<p>3. O produto recolhido nos termos da presente cl\u00e1usula ser\u00e1 examinado pela iHCare SA, que no caso de confirma\u00e7\u00e3o da desconformidade comunicar\u00e1, por correio eletr\u00f3nico, a substitui\u00e7\u00e3o do mesmo dentro de um prazo razo\u00e1vel.<\/p>\n<p>4. A substitui\u00e7\u00e3o do produto devolvido nos termos do presente artigo est\u00e1 condicionada \u00e0 disponibilidade do mesmo.<\/p>\n<p>5.Na impossibilidade de substitui\u00e7\u00e3o, o montante pago pelos produtos devolvidos com fundamento na sua desconformidade, ser\u00e1 reembolsado ao cliente, na sua totalidade, incluindo os custos de entrega suportados para a entrega do produto.<\/p>\n<p>6. Ser\u00e3o salvaguardados todos os direitos reconhecidos pela lei em vigor.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 11: TROCAS<\/strong><\/h3>\n<p class=\" translation-block\">Os produtos adquiridos atrav\u00e9s do site www.ihcarehealth.com n\u00e3o podem ser trocados.<\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">1. DEVOLU\u00c7\u00d5ES DE COMPRAS \u00c0 DIST\u00c2NCIA<\/span><\/span><\/span><\/strong><\/h4>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Para compras \u00e0 dist\u00e2ncia (online e a receber na morada via transportadora), a Lei Portuguesa estabelece ao consumidor um prazo de 14 dias, vulgarmente conhecido como \u201cper\u00edodo de reflex\u00e3o\u201d, ap\u00f3s tomar posse f\u00edsica dos bens, durante o qual pode devolver os artigos sem a necessidade de indicar um motivo.<\/span><\/span>\u00a0<\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Nos casos de livre resolu\u00e7\u00e3o de contrato, os portes de envio e de devolu\u00e7\u00e3o ficam a cargo do consumidor, conforme estipulado no n.\u00ba 2 do artigo 13\u00ba do Decreto-Lei n.\u00ba 24\/2014, de 14 de fevereiro.<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O prazo de 14 dias mencionado no par\u00e1grafo anterior conta-se a partir do dia em que o Cliente ou terceiro, indicado por aquele, adquira a posse f\u00edsica dos bens, que ser\u00e1 sempre determinado com a assinatura, pelo Cliente ou terceiro, aposta na nota de rece\u00e7\u00e3o da encomenda facultada pelo transportador.<\/span><\/span>\u00a0<\/span><\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2. CONDI\u00c7\u00d5ES DE ACEITA\u00c7\u00c3O DE DEVOLU\u00c7\u00d5ES\/TROCAS<\/span><\/span><\/span><\/strong><\/h4>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Apesar de serem aceites devolu\u00e7\u00f5es\/trocas dos bens fornecidos em compras \u00e0 dist\u00e2ncia, conforme descrito anteriormente, os bens devolvidos s\u00f3 ser\u00e3o aceites caso respeitem com rigor e de forma cumulativa as seguintes condi\u00e7\u00f5es:<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2.1 O artigo devolvido esteja intacto, sem qualquer marca\/dano de uso ou deprecia\u00e7\u00e3o;<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2.2 O Cliente devolva o artigo juntamente com a sua embalagem, manuais e acess\u00f3rios no mesmo estado em que lhe foram expedidos, sem qualquer anomalia;<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2.3 O artigo seja devolvido juntamente com a fatura respetiva;<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">2.4 O artigo seja devolvido dentro do prazo legal (14 dias) ap\u00f3s posse f\u00edsica do bem.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">No caso de incumprimento de qualquer das condi\u00e7\u00f5es supra mencionadas, a Ihcare n\u00e3o poder\u00e1 aceitar a devolu\u00e7\u00e3o, reembolso e\/ou a troca dos bens fornecidos.<\/span><\/span><\/span><\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">3. FORMA DE REEMBOLSO DE DEVOLU\u00c7\u00d5ES<\/span><\/span> <\/span><\/strong><\/h4>\n<p class=\" translation-block\">Caso o cliente pretenda o reembolso, este ser\u00e1 feito por transfer\u00eancia banc\u00e1ria para o IBAN que aquele expressamente indique, por escrito, no pedido de devolu\u00e7\u00e3o do bem fornecido. A IHcare far\u00e1 o reembolso do valor pago pelo bem fornecido, acrescido dos custos de devolu\u00e7\u00e3o do bem, se aplic\u00e1vel, no prazo de 14 dias e logo que seja recebido o bem pela IHcare, e s\u00f3 ap\u00f3s a verifica\u00e7\u00e3o t\u00e9cnica do estado do bem, para al\u00e9m do cumprimento das condi\u00e7\u00f5es descritas no ponto 1 da \u201dCondi\u00e7\u00f5es de aceita\u00e7\u00e3o de Devolu\u00e7\u00f5es\/Trocas\u201d.<\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00c9 permitida a reten\u00e7\u00e3o do reembolso enquanto os bens n\u00e3o forem recebidos pela Ihcare ou enquanto o cliente n\u00e3o apresentar prova da devolu\u00e7\u00e3o do bem.<\/span><\/span><\/span><\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">4. DAR IN\u00cdCIO AO PROCESSO DE DEVOLU\u00c7\u00c3O\/TROCA<\/span><\/span> <\/span><\/strong><\/h4>\n<p class=\" translation-block\">O processo de devolu\u00e7\u00e3o \u00e9 simples mas varia conforme a proveni\u00eancia da encomenda, pelo que o cliente dever\u00e1 contactar previamente a IHcare atrav\u00e9s do Servi\u00e7o de Apoio ao Cliente. Dentro dos limites estabelecidos na lei, a devolu\u00e7\u00e3o e o valor dos portes\/custos da devolu\u00e7\u00e3o ficam a cargo do cliente.<\/p>\n<p><span class=\"HwtZe\" lang=\"en\"> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A Ihcare n\u00e3o \u00e9 obrigada a reembolsar os custos adicionais de entrega quando o cliente solicitar, expressamente, uma modalidade de entrega diferente e mais onerosa do que a modalidade comumente aceite e menos onerosa proposta pela IHcare.<\/span><\/span><\/span><\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">5. RECOMENDA\u00c7\u00d5ES IHcare<\/span><\/span> <\/span><\/strong><\/h4>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A IHcare recomenda aos seus clientes o cumprimento do seguinte procedimento:<\/span><\/span><\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">5.1 Antes de adquirir um produto, certifique-se que o mesmo vai de encontro ao que pretende. A IHcare est\u00e1 dispon\u00edvel para esclarecer todas as d\u00favidas que queira colocar, por email, telefone ou atrav\u00e9s das redes sociais.<\/span><\/span>\u00a0<\/span><\/p>\n<p class=\" translation-block\">5.2 Depois de adquirido o produto, tenha sempre cuidado na abertura da caixa\/embalagem, e veja como est\u00e3o dispostos o produto, os acess\u00f3rios e os manuais dentro da embalagem. Em caso de devolu\u00e7\u00e3o, \u00e9 muito importante que sejam cumpridas todas as exig\u00eancias que constam das CONDI\u00c7\u00d5ES DE ACEITA\u00c7\u00c3O DE DEVOLU\u00c7\u00d5ES\/TROCAS, com especial destaque para os par\u00e1grafos 2.1 e 2.2.<\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">6 &#8211; PRODUTOS DEFEITUOSOS E DANIFICADOS<\/span><\/span><\/span><\/strong><\/h4>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Para a Ihcare, a qualidade \u00e9 primordial.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00c9 extremamente raro que os nossos produtos sejam vendidos ao p\u00fablico com algum dano ou defeito. A IHcare tem a obriga\u00e7\u00e3o legal de se certificar que os Produtos est\u00e3o em conformidade com o contrato de compra e venda celebrado.<\/span><\/span>\u00a0 <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Inspecionamos todos os Produtos alegadamente danificados ou defeituosos atrav\u00e9s de uma equipa t\u00e9cnica especializada. Se o dano for o resultado de um defeito de fabrico ou desvio das especifica\u00e7\u00f5es de f\u00e1brica, comprometemo-nos a reembolsar integralmente o custo do referido Produto defeituoso.<\/span><\/span>\u00a0<\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Na impossibilidade da repara\u00e7\u00e3o ou substitui\u00e7\u00e3o do produto, a IHCare proceder\u00e1 ao reembolso do valor da sua compra ou poder\u00e1 usar esse valor para compras na nossa loja, no prazo m\u00e1ximo de 3 meses.<\/span><\/span> <\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A IHCare reserva-se o direito de recusar a troca ou devolu\u00e7\u00e3o de produtos com sinais vis\u00edveis de uso, que tenham sido lavados ou transformados, que tenham as suas etiquetas removidas ou que n\u00e3o estejam na sua embalagem original, com todos os acess\u00f3rios completos e no seu estado original.<\/span><\/span>\u00a0<\/span><\/p>\n<p><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A nossa equipa de Apoio ao Cliente est\u00e1 dispon\u00edvel para o assistir em qualquer quest\u00e3o ou d\u00favida que tenha.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 12: MOTIVOS DE FOR\u00c7A MAIOR<\/strong><\/h3>\n<p>1. N\u00e3o seremos respons\u00e1veis por nenhum incumprimento ou atraso de alguma das obriga\u00e7\u00f5es por n\u00f3s assumidas ao abrigo de um contrato cuja causa se deva a acontecimentos que est\u00e3o fora do nosso controlo razo\u00e1vel, nomeadamente por motivos de For\u00e7a Maior.<\/p>\n<p>2. Os Motivos de For\u00e7a Maior incluem qualquer ato, acontecimento, falta de exerc\u00edcio, omiss\u00e3o ou acidente que esteja fora do nosso controlo razo\u00e1vel, incluindo, entre outros, os seguintes:<\/p>\n<ul>\n<li>\n<ul>\n<li>Greves, encerramentos por parte patronal ou outras medidas reivindicativas.<\/li>\n<li>Perturba\u00e7\u00f5es da ordem p\u00fablica, revoltas, invas\u00f5es, ataques ou amea\u00e7as terroristas, guerra (declarada ou n\u00e3o) ou amea\u00e7as ou preparativos de guerra.<\/li>\n<li>Inc\u00eandios, explos\u00f5es, tempestades, inunda\u00e7\u00f5es, terramotos, aluimentos, epidemias ou qualquer outro desastre natural.<\/li>\n<li>Impossibilidade de utilizar comboios, barcos, avi\u00f5es, transportes de motor ou outros meios de transporte, p\u00fablicos ou privados.<\/li>\n<li>Impossibilidade de utilizar sistemas p\u00fablicos ou privados de telecomunica\u00e7\u00f5es.<\/li>\n<li>Atos, decretos, legisla\u00e7\u00e3o, normas ou restri\u00e7\u00f5es de qualquer governo ou autoridade p\u00fablica.<\/li>\n<li>Greves, falhas ou acidentes do transporte mar\u00edtimo ou fluvial, postal ou qualquer outro tipo de transporte.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>3. Considerar-se-\u00e1 que as nossas obriga\u00e7\u00f5es derivadas dos contratos ficam suspensas durante o per\u00edodo em que se verificarem os Motivos de For\u00e7a Maior e beneficiaremos de um alargamento do prazo para cumprir tais obriga\u00e7\u00f5es, por um per\u00edodo de tempo igual ao da dura\u00e7\u00e3o dos Motivos de For\u00e7a Maior. Utilizaremos todos os meios razo\u00e1veis para fazer cessar os Motivos de For\u00e7a Maior ou para encontrar uma solu\u00e7\u00e3o que nos permita cumprir com as nossas obriga\u00e7\u00f5es decorrentes do contrato, apesar dos Motivos de For\u00e7a Maior.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 13: RESPONSABILIDADE<\/strong><\/h3>\n<p>1. Para todas as etapas de acesso ao site www.ihcarehealth.com,bem como do processo da encomenda, entrega e servi\u00e7os posteriores, a sociedade iHCare SA s\u00f3 possui uma obriga\u00e7\u00e3o de meios.<a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\"> www.ihcarehealth.com.<\/a><\/p>\n<p>2. A iHCare SA n\u00e3o garante nem se responsabiliza por quaisquer inconvenientes ou preju\u00edzos inerentes \u00e0 utiliza\u00e7\u00e3o da rede de internet, \u00e0 rutura de servi\u00e7o, \u00e0 intrus\u00e3o exterior ou \u00e0 presen\u00e7a de v\u00edrus inform\u00e1ticos, ou de qualquer outro caso de for\u00e7a maior.<\/p>\n<p>3. Os artigos vendidos est\u00e3o descritos e apresentados no site www.ihcarehealth.com, com o m\u00e1ximo de exatid\u00e3o poss\u00edvel.<\/p>\n<p>4. Se, apesar de todas as precau\u00e7\u00f5es, ocorrerem erros no site www.ihcarehealth.com, a iHCare SA n\u00e3o ser\u00e1 responsabilizada por esse facto.<\/p>\n<p>5. O disposto na presente cl\u00e1usula n\u00e3o afetar\u00e1 os direitos legais do cliente de desistir do contrato.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 14: MENOR DE IDADE<\/strong><\/h3>\n<p>N\u00e3o vendemos produtos a menores de idade.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 15: TRATAMENTO DE DADOS PESSOAIS E NEWSLETTER<\/strong><\/h3>\n<p>No cumprimento da lei portuguesa, relativa \u00e0 prote\u00e7\u00e3o de dados pessoais, a informa\u00e7\u00e3o ou os dados facultados pelo utilizador, ser\u00e3o tratados em conformidade com o estabelecido na nossa Pol\u00edtica de Privacidade.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 16: V\u00cdRUS, PIRATARIA E OUTROS ATAQUES INFORM\u00c1TICOS<\/strong><\/h3>\n<p class=\" translation-block\">A iHCare SA n\u00e3o se responsabiliza por quaisquer danos ou perdas resultantes de um ataque de navega\u00e7\u00e3o de servi\u00e7o, v\u00edrus ou qualquer outro programa ou material tecnologicamente prejudicial ou danoso, que possa afetar o computador do utilizador\/cliente, equipamento inform\u00e1tico, eletr\u00f3nico, dados ou materiais, em consequ\u00eancia da utiliza\u00e7\u00e3o do site www.ihcarehealth.com, ou do descarregamento de conte\u00fado do mesmo ou dos conte\u00fados para os quais o mesmo redirecione.<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 17: PROPRIEDADE INTELECTUAL<\/strong><\/h3>\n<p>1. Todos os elementos do site <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a>sejam eles visuais ou sonoros, incluindo a tecnologia subjacente, s\u00e3o protegidos pelos direitos de autor, das marcas ou das patentes.<br \/>\n2. O utilizador que disponha de um site pessoal na internet e que deseje colocar, para uso pessoal, no seu site um simples link direto \u00e0 homepage do site www.ihcarehealth.com, deve obrigatoriamente solicitar autoriza\u00e7\u00e3o \u00e0 sociedade iHCare SA. <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a>.<br \/>\n3. A autoriza\u00e7\u00e3o a que se refere o n\u00famero anterior s\u00f3 \u00e9 v\u00e1lida se prestada por escrito.<br \/>\n4. Qualquer link ou hipertexto direcionado ao site www.ihcarehealth.com, com utiliza\u00e7\u00e3o da t\u00e9cnica de framing ou de in-line linking \u00e9 formalmente proibido.<a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\"> www.ihcarehealth.com.<\/a><br \/>\n5. Em todos os casos, a utiliza\u00e7\u00e3o de qualquer link, incluindo os constantes nos n\u00bas 3 e 4 da presente cl\u00e1usula, mesmo tacitamente autorizados, dever\u00e3o ser retirados com um simples pedido da sociedade iHCare SA.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 18: PRIVACIDADE E PROTE\u00c7\u00c3O DE DADOS PESSOAIS<\/strong><\/h3>\n<p>Todos os Clientes t\u00eam o direito de acesso, retifica\u00e7\u00e3o, cancelamento e oposi\u00e7\u00e3o dos seus dados. Caso deseje, a qualquer momento, deixar de fazer parte da base de dados da iHCare SA poder\u00e1 exercer este direito enviando um email para <a href=\"mailto:support@ihcare.pt\">support@ihcare.pt<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 19 : ACORDO TOTAL<\/strong><\/h3>\n<p>1. As presentes condi\u00e7\u00f5es gerais de venda constituem o acordo total entre as partes em refer\u00eancia.<br \/>\n2. Caso uma das cl\u00e1usulas das presentes condi\u00e7\u00f5es se torne nula e sem valor, em virtude de uma altera\u00e7\u00e3o legislativa, normativa ou por senten\u00e7a, a mesma dever\u00e1 considerar-se n\u00e3o escrita, permanecendo as restantes cl\u00e1usulas e condi\u00e7\u00f5es, por princ\u00edpio, plenamente v\u00e1lidas n\u00e3o sendo afetadas pelas cl\u00e1usulas anuladas ou invalidadas.<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 20: DIREITO DE ALTERA\u00c7\u00c3O UNILATERAL DAS CONDI\u00c7\u00d5ES<\/strong><\/h3>\n<p>1. As presentes condi\u00e7\u00f5es podem ser objeto de altera\u00e7\u00e3o a qualquer momento.<br \/>\n2. O utilizador\/cliente est\u00e1 sujeito \u00e0s pol\u00edticas e condi\u00e7\u00f5es em vigor no momento em que se encontra a utilizar o site <a href=\"https:\/\/ihcarehealth.com\/pt\/\" target=\"_blank\" rel=\"noopener\">www.ihcarehealth.com<\/a>, ou formalize a sua encomenda, salvo quando, por lei ou decis\u00e3o de organismos governamentais, sejam feitas altera\u00e7\u00f5es, com car\u00e1cter retroativo, nessas pol\u00edticas, condi\u00e7\u00f5es ou declara\u00e7\u00e3o de privacidade;<br \/>\n3. No caso previsto no n\u00famero anterior, as altera\u00e7\u00f5es tamb\u00e9m afetar\u00e3o as encomendas que o utilizador\/cliente tenha formalizado ao abrigo das condi\u00e7\u00f5es objeto de altera\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 21: DURA\u00c7\u00c3O<\/strong><\/h3>\n<p>1. As presentes condi\u00e7\u00f5es aplicam-se na dura\u00e7\u00e3o dos servi\u00e7os oferecidos pela sociedade iHCare SA.<br \/>\n2. Todos os artigos exclusivos do site s\u00e3o v\u00e1lidos at\u00e9 ao limite dos stocks dispon\u00edveis.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARTIGO 22: RAL- RESOLU\u00c7\u00c3O ALTERNATIVA DE LIT\u00cdGIOS<\/strong><\/h3>\n<p>No cumprimento do disposto na Lei n\u00ba 144\/2015 de 08 de Setembro, informam-se todos os consumidores que, em caso de lit\u00edgio derivado dos nossos fornecimentos de bens e servi\u00e7os poder\u00e3o recorrer a uma Entidade Alternativa de Lit\u00edgios de Consumo, infra identificadas:<\/p>\n<ul>\n<li>Centro de Arbitragem de Conflitos de Consumo do Vale do Ave \/ Tribunal Arbitral<br \/>\nEmail: <a href=\"mailto:triave@gmail.com\">triave@gmail.com<\/a><br \/>\nTel: 253 422 410<\/li>\n<li>Centro de Informa\u00e7\u00e3o de Consumo e Arbitragem do Porto<br \/>\nEmail: <a href=\"mailto:cicap@mail.telepac.pt\">cicap@mail.telepac.pt<\/a><br \/>\nTel: 225 508 349 \/225 029 791<\/li>\n<li>Centro de Arbitragem de Conflitos de Consumo de Lisboa<br \/>\nEmail: <a href=\"mailto:juridico@centroarbitragemlisboa.pt\">juridico@centroarbitragemlisboa.pt<\/a> \/ <a href=\"mailto:director@centroarbitragemlisboa.pt\">director@centroarbitragemlisboa.pt<\/a><br \/>\nTel: 218 807 030<\/li>\n<li>Centro Nacional de Informa\u00e7\u00e3o e Arbitragem de Conflitos de Consumo<br \/>\nEmail: cniacc@unl.pt<br \/>\nTel: 213 847 484<\/li>\n<li>Centro de Informa\u00e7\u00e3o, Media\u00e7\u00e3o e Arbitragem de Conflitos de Consumo do Algarve<br \/>\nEmail: <a href=\"mailto:support@consumidoronline.pt\">support@consumidoronline.pt<\/a><br \/>\nTel: 289 823 135<\/li>\n<\/ul>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Termos e Condi\u00e7\u00f5es Em conformidade com a Lei n.\u00ba 47\/2014, de 28 de Julho, o presente documento estabelece as condi\u00e7\u00f5es a observar no uso do site www.ihcarehealth.com, bem como no...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1679","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/pages\/1679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/comments?post=1679"}],"version-history":[{"count":12,"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/pages\/1679\/revisions"}],"predecessor-version":[{"id":3270,"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/pages\/1679\/revisions\/3270"}],"wp:attachment":[{"href":"https:\/\/myshellty.com\/pt\/wp-json\/wp\/v2\/media?parent=1679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}